{"id":794,"count":19,"description":"","link":"https:\/\/ebuys.co\/no\/product-category\/kitchen-gourmet\/gourmet\/","name":"Gourmet","slug":"gourmet","taxonomy":"product_cat","parent":792,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/ebuys.co\/no\/wp-json\/wp\/v2\/product_cat\/794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebuys.co\/no\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ebuys.co\/no\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ebuys.co\/no\/wp-json\/wp\/v2\/product_cat\/792"}],"wp:post_type":[{"href":"https:\/\/ebuys.co\/no\/wp-json\/wp\/v2\/product?product_cat=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}