{"id":1793,"count":11,"description":"","link":"https:\/\/ebuys.co\/de\/product-category\/kitchen-gourmet\/small-electrical-appliances\/fryers\/","name":"Fryers","slug":"fryers","taxonomy":"product_cat","parent":887,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/ebuys.co\/de\/wp-json\/wp\/v2\/product_cat\/1793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebuys.co\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ebuys.co\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ebuys.co\/de\/wp-json\/wp\/v2\/product_cat\/887"}],"wp:post_type":[{"href":"https:\/\/ebuys.co\/de\/wp-json\/wp\/v2\/product?product_cat=1793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}